{"id":68,"count":43,"description":"","link":"https:\/\/www.saventic.com\/es\/department\/medical\/","name":"Medical","slug":"medical","taxonomy":"department","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Medical Archives - Saventic Health<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.saventic.com\/department\/medical\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Medical Archives - Saventic Health\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.saventic.com\/department\/medical\/\" \/>\n<meta property=\"og:site_name\" content=\"Saventic Health\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.saventic.com\/department\/medical\/\",\"url\":\"https:\/\/www.saventic.com\/department\/medical\/\",\"name\":\"Medical Archives - Saventic Health\",\"isPartOf\":{\"@id\":\"https:\/\/www.saventic.com\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.saventic.com\/department\/medical\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.saventic.com\/department\/medical\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.saventic.com\/es\/pagina-principal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Medical\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.saventic.com\/#website\",\"url\":\"https:\/\/www.saventic.com\/\",\"name\":\"Saventic Health\",\"description\":\"AI-driven technology for rare diseases\",\"publisher\":{\"@id\":\"https:\/\/www.saventic.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.saventic.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.saventic.com\/#organization\",\"name\":\"Saventic Health\",\"url\":\"https:\/\/www.saventic.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.saventic.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.saventic.com\/wp-content\/uploads\/2025\/02\/Logo.svg\",\"contentUrl\":\"https:\/\/www.saventic.com\/wp-content\/uploads\/2025\/02\/Logo.svg\",\"width\":280,\"height\":66,\"caption\":\"Saventic Health\"},\"image\":{\"@id\":\"https:\/\/www.saventic.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Medical Archives - Saventic Health","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.saventic.com\/department\/medical\/","og_locale":"es_ES","og_type":"article","og_title":"Medical Archives - Saventic Health","og_url":"https:\/\/www.saventic.com\/department\/medical\/","og_site_name":"Saventic Health","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.saventic.com\/department\/medical\/","url":"https:\/\/www.saventic.com\/department\/medical\/","name":"Medical Archives - Saventic Health","isPartOf":{"@id":"https:\/\/www.saventic.com\/#website"},"breadcrumb":{"@id":"https:\/\/www.saventic.com\/department\/medical\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/www.saventic.com\/department\/medical\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.saventic.com\/es\/pagina-principal\/"},{"@type":"ListItem","position":2,"name":"Medical"}]},{"@type":"WebSite","@id":"https:\/\/www.saventic.com\/#website","url":"https:\/\/www.saventic.com\/","name":"Saventic Health","description":"AI-driven technology for rare diseases","publisher":{"@id":"https:\/\/www.saventic.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.saventic.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.saventic.com\/#organization","name":"Saventic Health","url":"https:\/\/www.saventic.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.saventic.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.saventic.com\/wp-content\/uploads\/2025\/02\/Logo.svg","contentUrl":"https:\/\/www.saventic.com\/wp-content\/uploads\/2025\/02\/Logo.svg","width":280,"height":66,"caption":"Saventic Health"},"image":{"@id":"https:\/\/www.saventic.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.saventic.com\/es\/wp-json\/wp\/v2\/department\/68","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.saventic.com\/es\/wp-json\/wp\/v2\/department"}],"about":[{"href":"https:\/\/www.saventic.com\/es\/wp-json\/wp\/v2\/taxonomies\/department"}],"wp:post_type":[{"href":"https:\/\/www.saventic.com\/es\/wp-json\/wp\/v2\/employee?department=68"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}