{"id":5465,"date":"2025-07-08T07:56:02","date_gmt":"2025-07-08T07:56:02","guid":{"rendered":"https:\/\/tst.saventic.com\/employee\/marek-dudzinski-phd\/"},"modified":"2025-09-11T18:33:53","modified_gmt":"2025-09-11T18:33:53","slug":"marek-dudzinski-phd","status":"publish","type":"employee","link":"https:\/\/www.saventic.com\/es\/employee\/marek-dudzinski-phd\/","title":{"rendered":"Marek Dudzi\u0144ski, PhD"},"template":"","meta":{"_acf_changed":false},"department":[66],"class_list":["post-5465","employee","type-employee","status-publish","hentry","department-operations"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Marek Dudzi\u0144ski, PhD - Saventic Health<\/title>\n<meta name=\"description\" content=\"El Dr. Marek Dudzi\u0144ski es especialista en medicina interna y hematolog\u00eda, director m\u00e9dico de Saventic Health e investigador en trastornos hematol\u00f3gicos cr\u00f3nicos y el uso del aprendizaje autom\u00e1tico en medicina. Es autor publicado y miembro fundador de importantes asociaciones m\u00e9dicas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.saventic.com\/es\/employee\/marek-dudzinski-phd\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marek Dudzi\u0144ski, PhD - Saventic Health\" \/>\n<meta property=\"og:description\" content=\"El Dr. Marek Dudzi\u0144ski es especialista en medicina interna y hematolog\u00eda, director m\u00e9dico de Saventic Health e investigador en trastornos hematol\u00f3gicos cr\u00f3nicos y el uso del aprendizaje autom\u00e1tico en medicina. Es autor publicado y miembro fundador de importantes asociaciones m\u00e9dicas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.saventic.com\/es\/employee\/marek-dudzinski-phd\/\" \/>\n<meta property=\"og:site_name\" content=\"Saventic Health\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-11T18:33:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.saventic.com\/es\/employee\/marek-dudzinski-phd\/\",\"url\":\"https:\/\/www.saventic.com\/es\/employee\/marek-dudzinski-phd\/\",\"name\":\"Marek Dudzi\u0144ski, PhD - Saventic Health\",\"isPartOf\":{\"@id\":\"https:\/\/www.saventic.com\/#website\"},\"datePublished\":\"2025-07-08T07:56:02+00:00\",\"dateModified\":\"2025-09-11T18:33:53+00:00\",\"description\":\"El Dr. Marek Dudzi\u0144ski es especialista en medicina interna y hematolog\u00eda, director m\u00e9dico de Saventic Health e investigador en trastornos hematol\u00f3gicos cr\u00f3nicos y el uso del aprendizaje autom\u00e1tico en medicina. Es autor publicado y miembro fundador de importantes asociaciones m\u00e9dicas.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.saventic.com\/es\/employee\/marek-dudzinski-phd\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.saventic.com\/es\/employee\/marek-dudzinski-phd\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.saventic.com\/es\/employee\/marek-dudzinski-phd\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.saventic.com\/es\/pagina-principal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Marek Dudzi\u0144ski, PhD\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.saventic.com\/#website\",\"url\":\"https:\/\/www.saventic.com\/\",\"name\":\"Saventic Health\",\"description\":\"AI-driven technology for rare diseases\",\"publisher\":{\"@id\":\"https:\/\/www.saventic.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.saventic.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.saventic.com\/#organization\",\"name\":\"Saventic Health\",\"url\":\"https:\/\/www.saventic.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.saventic.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.saventic.com\/wp-content\/uploads\/2025\/02\/Logo.svg\",\"contentUrl\":\"https:\/\/www.saventic.com\/wp-content\/uploads\/2025\/02\/Logo.svg\",\"width\":280,\"height\":66,\"caption\":\"Saventic Health\"},\"image\":{\"@id\":\"https:\/\/www.saventic.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Marek Dudzi\u0144ski, PhD - Saventic Health","description":"El Dr. Marek Dudzi\u0144ski es especialista en medicina interna y hematolog\u00eda, director m\u00e9dico de Saventic Health e investigador en trastornos hematol\u00f3gicos cr\u00f3nicos y el uso del aprendizaje autom\u00e1tico en medicina. Es autor publicado y miembro fundador de importantes asociaciones m\u00e9dicas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.saventic.com\/es\/employee\/marek-dudzinski-phd\/","og_locale":"es_ES","og_type":"article","og_title":"Marek Dudzi\u0144ski, PhD - Saventic Health","og_description":"El Dr. Marek Dudzi\u0144ski es especialista en medicina interna y hematolog\u00eda, director m\u00e9dico de Saventic Health e investigador en trastornos hematol\u00f3gicos cr\u00f3nicos y el uso del aprendizaje autom\u00e1tico en medicina. Es autor publicado y miembro fundador de importantes asociaciones m\u00e9dicas.","og_url":"https:\/\/www.saventic.com\/es\/employee\/marek-dudzinski-phd\/","og_site_name":"Saventic Health","article_modified_time":"2025-09-11T18:33:53+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.saventic.com\/es\/employee\/marek-dudzinski-phd\/","url":"https:\/\/www.saventic.com\/es\/employee\/marek-dudzinski-phd\/","name":"Marek Dudzi\u0144ski, PhD - Saventic Health","isPartOf":{"@id":"https:\/\/www.saventic.com\/#website"},"datePublished":"2025-07-08T07:56:02+00:00","dateModified":"2025-09-11T18:33:53+00:00","description":"El Dr. Marek Dudzi\u0144ski es especialista en medicina interna y hematolog\u00eda, director m\u00e9dico de Saventic Health e investigador en trastornos hematol\u00f3gicos cr\u00f3nicos y el uso del aprendizaje autom\u00e1tico en medicina. Es autor publicado y miembro fundador de importantes asociaciones m\u00e9dicas.","breadcrumb":{"@id":"https:\/\/www.saventic.com\/es\/employee\/marek-dudzinski-phd\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.saventic.com\/es\/employee\/marek-dudzinski-phd\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.saventic.com\/es\/employee\/marek-dudzinski-phd\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.saventic.com\/es\/pagina-principal\/"},{"@type":"ListItem","position":2,"name":"Marek Dudzi\u0144ski, PhD"}]},{"@type":"WebSite","@id":"https:\/\/www.saventic.com\/#website","url":"https:\/\/www.saventic.com\/","name":"Saventic Health","description":"AI-driven technology for rare diseases","publisher":{"@id":"https:\/\/www.saventic.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.saventic.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.saventic.com\/#organization","name":"Saventic Health","url":"https:\/\/www.saventic.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.saventic.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.saventic.com\/wp-content\/uploads\/2025\/02\/Logo.svg","contentUrl":"https:\/\/www.saventic.com\/wp-content\/uploads\/2025\/02\/Logo.svg","width":280,"height":66,"caption":"Saventic Health"},"image":{"@id":"https:\/\/www.saventic.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.saventic.com\/es\/wp-json\/wp\/v2\/employee\/5465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.saventic.com\/es\/wp-json\/wp\/v2\/employee"}],"about":[{"href":"https:\/\/www.saventic.com\/es\/wp-json\/wp\/v2\/types\/employee"}],"wp:attachment":[{"href":"https:\/\/www.saventic.com\/es\/wp-json\/wp\/v2\/media?parent=5465"}],"wp:term":[{"taxonomy":"department","embeddable":true,"href":"https:\/\/www.saventic.com\/es\/wp-json\/wp\/v2\/department?post=5465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}